{"id":39048,"date":"2023-01-19T14:41:35","date_gmt":"2023-01-19T13:41:35","guid":{"rendered":"https:\/\/www.wallix.com\/?p=39048"},"modified":"2025-11-18T14:58:24","modified_gmt":"2025-11-18T13:58:24","slug":"wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole","status":"publish","type":"post","link":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/","title":{"rendered":"WALLIX reconnu \u00ab\u00a0Overall Leader\u00a0\u00bb par le cabinet d&rsquo;analystes KuppingerCole"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_two_third  avia-builder-el-first   container_wrap fullsize'  ><div  class='avia-slideshow av-lqweczmp-9043ffdb3169d9eb83217bec8a55e284 avia-slideshow-featured av_slideshow_full avia-slide-slider av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied  image_no_stretch avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 28.666666666667%;'><li  class='avia-slideshow-slide av-lqweczmp-9043ffdb3169d9eb83217bec8a55e284__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><div class='av-slideshow-caption av-lqweczmp-9043ffdb3169d9eb83217bec8a55e284__0 caption_fullwidth caption_bottom caption_bottom_framed caption_framed'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >WALLIX reconnu \"Overall Leader\" par le cabinet d\u2019analystes KuppingerCole<\/h2><\/div><\/div><\/div><\/div><\/div><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-29335 avia-img-lazy-loading-not-29335\"  src=\"https:\/\/www.wallix.com\/wp-content\/uploads\/2022\/12\/AdobeStock_429258682-copie-1500x430.jpg\" width=\"1500\" height=\"430\" title='Ligne d&#039;onde abstraite 035' alt='Illustration de la s\u00e9curit\u00e9 num\u00e9rique, soulignant l&#039;importance de la protection des donn\u00e9es sensibles dans un monde connect\u00e9.'  itemprop=\"thumbnailUrl\"   \/><div class='av-section-color-overlay' style='opacity: 1; background-image: url(https:\/\/www.wallix.com\/wp-content\/uploads\/2022\/12\/AdobeStock_429258682-copie-1500x630.jpg); background-repeat: repeat;'><\/div><\/div><\/li><\/ul><\/div><\/div><div id='after_full_slider_1'  class='main_color av_default_container_wrap container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-39048'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-av_two_third-7714eba142aeda1f8b5272a3c372b279 av_two_third  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_one_third  avia-builder-el-first  first flex_column_div  '     ><section  class='av_textblock_section av-lqweeaua-c3706045a60ce59e430e89a0f105459d '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><ul>\n<li><strong><em>WALLIX<\/em><\/strong> <strong><em>PAM<\/em><\/strong><em> a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait ainsi que <\/em><strong><em>WALLIX PA<\/em><\/strong><em>est une solution Compl\u00e8te et performante, avec de nombreuses fonctionnalit\u00e9s.<\/em><\/li>\n<\/ul>\n<ul>\n<li><em>KuppingerCole souligne \u00e9galement la capacit\u00e9 d&rsquo;innovation de <\/em><strong><em>WALLIX<\/em><\/strong><em> en enrichissant ses technologies chaque ann\u00e9e pour proposer une solution continuellement \u00e0 l&rsquo;\u00e9tat de l&rsquo;art en mati\u00e8re de s\u00e9curisation et des acc\u00e8s et des identit\u00e9s num\u00e9riques<\/em><\/li>\n<\/ul>\n<ul>\n<li><em>Enfin, KuppingerCole reconnait que <\/em><strong><em>WALLIX PAM<\/em><\/strong><em> est une solution qui a \u00e9t\u00e9 \u00e9prouv\u00e9e par des organisations du monde entier, tous secteurs confondus et notamment par l&rsquo;industrie, un des secteurs les plus critiques aujourd&rsquo;hui.<\/em><\/li>\n<\/ul>\n<p><strong>Paris, 19 janvier 2023<\/strong> \u2013 <a href=\"https:\/\/www.wallix.com\/fr\/\"><strong>WALLIX<\/strong><\/a><strong>, (Euronext ALLIX) \u00e9diteur europ\u00e9en de logiciels de cybers\u00e9curit\u00e9 et expert en s\u00e9curisation des acc\u00e8s et des identit\u00e9s<\/strong>, obtient pour la 3\u00e8me ann\u00e9e cons\u00e9cutive la plus haute distinction &#8211; \u00ab\u00a0Overall Leader\u00a0\u00bb &#8211; du rapport Leadership Compass 2023 r\u00e9alis\u00e9 par le cabinet d&rsquo;analystes KuppingerCole, qui classe les acteurs mondiaux du PAM (Privileged Access Management).<\/p>\n<p>Chaque ann\u00e9e, KuppingerCole r\u00e9alise son rapport : le Leadership Compass. Il a pour objectif de fournir aux entreprises une vue d\u2019ensemble des diff\u00e9rents \u00e9diteurs de solutions informatiques existants, par domaine, et d\u2019identifier quels sont les leaders. Ainsi, le Leadership Compass est un v\u00e9ritable outil d\u2019aide \u00e0 la d\u00e9cision d\u2019achat.<\/p>\n<p>Le Leadership Compass classe les \u00e9diteurs parmi 4 cat\u00e9gories :<\/p>\n<ul>\n<li><strong><u>Market Leaders<\/u><\/strong> : pour les \u00e9diteurs qui disposent d\u2019une large base de client\u00e8le mondiale et d\u2019un solide r\u00e9seau de partenaires pour vendre leurs solutions.<\/li>\n<li><strong><u>Product Leaders<\/u><\/strong> : pour les \u00e9diteurs qui ont des produits de pointe, matures, qui r\u00e9pondent dans une large mesure aux attentes des analystes de KuppingerCole.<\/li>\n<li><strong><u>Innovation Leaders<\/u><\/strong> : pour les \u00e9diteurs qui stimulent l\u2019innovation dans leur domaine en fournissant les fonctionnalit\u00e9s les plus innovantes et prometteuses du march\u00e9.<\/li>\n<li><strong><u>Overall Leaders<\/u><\/strong> : pour les \u00e9diteurs qui, suite \u00e0 une \u00e9valuation combin\u00e9e des 3 pr\u00e9c\u00e9dentes cat\u00e9gories, obtiennent un r\u00e9sultat global au-dessus de la moyenne et dominent ainsi le march\u00e9.<\/li>\n<\/ul>\n<p><strong>WALLIX PAM, une solution compl\u00e8te, solide, pour tous les secteurs, avec une expertise forte de l\u2019industrie.<\/strong><\/p>\n<p>Dans le cadre de sa strat\u00e9gie de d\u00e9veloppement \u00ab\u00a0Le PAM pour tous\u00a0\u00bb, WALLIX a lanc\u00e9 l&rsquo;an dernier WALLIX PAM, une solution unifi\u00e9e regroupant toutes les technologies de WALLIX, permettant de s\u00e9curiser tous les acc\u00e8s et identit\u00e9s num\u00e9riques des organisations &#8211; humains ou machines &#8211; selon le principe du moindre privil\u00e8ge.<\/p>\n<p>Cette strat\u00e9gie obtient aujourd&rsquo;hui la reconnaissance de KuppingerCole qui consid\u00e8re que WALLIX PAM est une solution compl\u00e8te et performante, avec de nombreuses fonctionnalit\u00e9s, gr\u00e2ce \u00e0 la combinaison des technologies de :<\/p>\n<ul>\n<li>Gestion des sessions<\/li>\n<li>Gestion des mots de passe (humains, machines et applications)<\/li>\n<li>Authentification multifactorielle (MFA)<\/li>\n<li>Gestion des acc\u00e8s distants<\/li>\n<li>Gestion de l\u2019\u00e9l\u00e9vation et la d\u00e9l\u00e9gation de privil\u00e8ges (PEDM)<\/li>\n<\/ul>\n<p>KuppingerCole souligne \u00e9galement la capacit\u00e9 d&rsquo;innovation de WALLIX en enrichissant ses technologies chaque ann\u00e9e pour proposer une solution continuellement \u00e0 l&rsquo;\u00e9tat de l&rsquo;art en mati\u00e8re de s\u00e9curisation et des acc\u00e8s et des identit\u00e9s num\u00e9riques.<\/p>\n<p>Enfin, KuppingerCole reconnait que WALLIX PAM est une solution qui a \u00e9t\u00e9 \u00e9prouv\u00e9e par des organisations du monde entier, tous secteurs confondus et notamment par l&rsquo;industrie, un des secteurs les plus critiques aujourd&rsquo;hui. La cybers\u00e9curit\u00e9 industrielle est en effet au c\u0153ur du savoir-faire de WALLIX. Cette expertise sp\u00e9cifique s&rsquo;illustre au travers de sa marque OT.security by WALLIX.<\/p>\n<p>Ainsi, WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res : s\u00e9curit\u00e9, fonctionnalit\u00e9s, interop\u00e9rabilit\u00e9, facilit\u00e9 d\u2019usage et d\u00e9ploiement, positionnant WALLIX en Overall Leader du Leadership Compass 2022.<\/p>\n<p>\u00ab <em>L&rsquo;approche \u00ab\u00a0le PAM pour tous\u00a0\u00bb, avec la solution WALLIX PAM, est en ad\u00e9quation avec les besoins actuels du march\u00e9 en mati\u00e8re de s\u00e9curisation des acc\u00e8s et des identit\u00e9s num\u00e9riques. De plus, gr\u00e2ce \u00e0 la capacit\u00e9 d&rsquo;innovation de WALLIX, PAM dispose d\u00e9sormais de fonctionnalit\u00e9s tr\u00e8s avanc\u00e9es, offrant ainsi une solution vraiment comp\u00e9titive, qui doit s\u00e9rieusement \u00eatre \u00e9tudi\u00e9e par les entreprises.<\/em> \u00bb extrait du <strong>rapport Leader Compass 2022 de Kuppingercole<\/strong>.<\/p>\n<p>\u00ab\u00a0<em>La reconnaissance de KuppingerCole, s&rsquo;ajoutant \u00e0 celle de Quadrant Knowledge Solutions, de Frost &amp; Sullivan et du Gartner, prouve la pertinence et l&rsquo;efficacit\u00e9 de notre strat\u00e9gie tant du point de vue organisationnel que technologique. Cela refl\u00e8te \u00e9galement notre r\u00f4le de partenaire mondial de confiance pour tous les secteurs et notamment l&rsquo;industrie. Notre approche unique combine les meilleures solutions logicielles de leur cat\u00e9gorie avec des fonctionnalit\u00e9s compl\u00e8tes con\u00e7ues pour les besoins sp\u00e9cifiques des organisations et une exp\u00e9rience client in\u00e9gal\u00e9e.<\/em>\u00a0\u00bb affirme <strong>Edwige Brossard, Directrice Produit &amp; Marketing de WALLIX<\/strong>.<\/p>\n<h5><span style=\"color: #f4913a;\">\u00c0 PROPOS DE WALLIX<\/span><\/h5>\n<p>\u00c9diteur de logiciels de cybers\u00e9curit\u00e9, WALLIX est le sp\u00e9cialiste europ\u00e9en de la s\u00e9curisation des acc\u00e8s et des identit\u00e9s num\u00e9riques. Les technologies de WALLIX permettent aux entreprises de r\u00e9pondre aux enjeux actuels de protection des donn\u00e9es. Elles garantissent la d\u00e9tection et la r\u00e9silience aux cyberattaques permettant ainsi la continuit\u00e9 d&rsquo;activit\u00e9. Elles assurent \u00e9galement la mise en conformit\u00e9 aux exigences r\u00e9glementaires concernant l&rsquo;acc\u00e8s aux infrastructures informatiques et aux donn\u00e9es critiques. WALLIX s&rsquo;appuie sur un r\u00e9seau de plus de 300 revendeurs et int\u00e9grateurs \u00e0 travers le monde. Cot\u00e9e sur Euronext (ALLIX), WALLIX accompagne plus de 2000 organisations dans la s\u00e9curisation de leur transformation num\u00e9rique.<\/p>\n<p>OT Security by WALLIX est une marque de WALLIX d\u00e9di\u00e9e \u00e0 la s\u00e9curisation des acc\u00e8s et des identit\u00e9s num\u00e9riques dans les environnements industriels.<\/p>\n<p>WALLIX affirme sa responsabilit\u00e9 num\u00e9rique et s\u2019engage \u00e0 contribuer \u00e0 la construction d\u2019un espace num\u00e9rique europ\u00e9en de confiance, garant de la s\u00e9curit\u00e9 et de la confidentialit\u00e9 des donn\u00e9es des organisations mais \u00e9galement pour tout individu soucieux de la protection de son identit\u00e9 num\u00e9rique et du respect de sa vie priv\u00e9e. Le num\u00e9rique, qu\u2019il soit pour des usages professionnels ou personnels, doit \u00eatre \u00e9thique et responsable afin de vivre une transformation num\u00e9rique soci\u00e9tale s\u00e9curis\u00e9e et respectueuse des libert\u00e9s individuelles.<\/p>\n<p><a href=\"https:\/\/www.wallix.com\"><strong>www.wallix.com<\/strong><\/a><strong> | <\/strong><a href=\"mailto:info@wallix.com\"><strong>info@wallix.com<\/strong><\/a><\/p>\n<h5><span style=\"color: #f4913a;\">CONTACTS COMMUNICATION FINANCI\u00c8RE<\/span><\/h5>\n<p><strong>ACTUS Finance &amp; Communication<\/strong><\/p>\n<p>Relations Investisseurs &#8211; H\u00e9l\u00e8ne DE WATTEVILLE<br \/>\n01 53 67 36 33 \/ <a href=\"mailto:wallix@actus.fr\">WALLIX@actus.fr<\/a><\/p>\n<p>Relations Presse &#8211; D\u00e9borah SCHWARTZ<br \/>\n06 27 09 05 73 \/ <a href=\"mailto:dschwartz@actus.fr\">dschwartz@actus.fr<\/a><\/p>\n<\/div><\/section><\/div><div  class='flex_column av-av_one_third-f1c518e9ff58e869f80c8f093487abc9 av_one_third  avia-builder-el-3  el_after_av_two_third  avia-builder-el-last  flex_column_div  '     ><p><div  class='av-social-sharing-box av-av_social_share-9fde5520d696953ed33a93247d122c72 av-social-sharing-box-default  avia-builder-el-4  el_before_av_hr  avia-builder-el-first  av-social-sharing-box-fullwidth'><div class=\"av-share-box\"><h5 class='av-share-link-description av-no-toc '>Partager le communiqu\u00e9 de presse<\/h5><ul class=\"av-share-box-list noLightbox\"><li class='av-share-link av-social-link-twitter avia_social_iconfont' ><a target=\"_blank\" aria-label=\"Partager sur X\" href='https:\/\/twitter.com\/share?text=WALLIX%20reconnu%20%C2%AB%C2%A0Overall%20Leader%C2%A0%C2%BB%20par%20le%20cabinet%20d%E2%80%99analystes%20KuppingerCole&#038;url=https:\/\/www.wallix.com\/fr\/?p=39048' data-av_icon='\ue932' data-av_iconfont='entypo-fontello'  title='' data-avia-related-tooltip='Partager sur X'><span class='avia_hidden_link_text'>Partager sur X<\/span><\/a><\/li><li class='av-share-link av-social-link-linkedin avia_social_iconfont' ><a target=\"_blank\" aria-label=\"Partager sur LinkedIn\" href='https:\/\/linkedin.com\/shareArticle?mini=true&#038;title=WALLIX%20reconnu%20%C2%AB%C2%A0Overall%20Leader%C2%A0%C2%BB%20par%20le%20cabinet%20d%E2%80%99analystes%20KuppingerCole&#038;url=https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/' data-av_icon='\ue8fc' data-av_iconfont='entypo-fontello'  title='' data-avia-related-tooltip='Partager sur LinkedIn'><span class='avia_hidden_link_text'>Partager sur LinkedIn<\/span><\/a><\/li><li class='av-share-link av-social-link-mail avia_social_iconfont' ><a  aria-label=\"Partager par Mail\" href='mailto:?subject=WALLIX%20reconnu%20%C2%AB%C2%A0Overall%20Leader%C2%A0%C2%BB%20par%20le%20cabinet%20d%E2%80%99analystes%20KuppingerCole&#038;body=https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/' data-av_icon='\ue805' data-av_iconfont='entypo-fontello'  title='' data-avia-related-tooltip='Partager par Mail'><span class='avia_hidden_link_text'>Partager par Mail<\/span><\/a><\/li><\/ul><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3cdc9664f29087702913853352eac422\">\n#top .hr.hr-invisible.av-av_hr-3cdc9664f29087702913853352eac422{\nheight:10px;\n}\n<\/style>\n<div  class='hr av-av_hr-3cdc9664f29087702913853352eac422 hr-invisible  avia-builder-el-5  el_after_av_social_share  el_before_av_heading '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-040bc61f5641f45fc1cf88d91b8f7592\">\n#top .av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 av-special-heading-h3 blockquote modern-quote  avia-builder-el-6  el_after_av_hr  el_before_av_hr '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Communiqu\u00e9 de presse<\/h3><div class='av-subheading av-subheading_below'><p>2024<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3cdc9664f29087702913853352eac422\">\n#top .hr.hr-invisible.av-av_hr-3cdc9664f29087702913853352eac422{\nheight:10px;\n}\n<\/style>\n<div  class='hr av-av_hr-3cdc9664f29087702913853352eac422 hr-invisible  avia-builder-el-7  el_after_av_heading  el_before_av_magazine '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  id=\"avia-magazine-1\"  class='av-magazine av-ls3gad3i-127675d98c473e377add691bd3b49105  avia-builder-el-8  el_after_av_hr  el_before_av_heading   avia-builder-el-8  el_after_av_hr  el_before_av_heading ' ><div class='av-magazine-group sort_all'><article class='av-magazine-entry av-magazine-entry-id-64896 av-magazine-format-standard av-magazine-type-post av-magazine-entry-1 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX One Enterprise Vault, le gestionnaire de mots de passe personnel s\u00e9curis\u00e9 qui renforce la productivit\u00e9 et la conformit\u00e9 des entreprises\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2024-10-28T13:51:15+01:00\" >28 Octobre 2024<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2024-fr\/wallix-one-enterprise-vault-le-gestionnaire-de-mots-de-passe-personnel-securise-qui-stimule-la-productivite-et-la-conformite-des-entreprises\/' title='Lier vers : WALLIX One Enterprise Vault, le gestionnaire de mots de passe personnel s\u00e9curis\u00e9 qui renforce la productivit\u00e9 et la conformit\u00e9 des entreprises'>WALLIX One Enterprise Vault, le gestionnaire de mots de passe personnel s\u00e9curis\u00e9 qui renforce la productivit\u00e9 et la conformit\u00e9 des entreprises<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-64069 av-magazine-format-standard av-magazine-type-post av-magazine-entry-2 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX parmi les leaders mondiaux du PAM avec une mention sp\u00e9ciale pour s\u00e9curiser les environnements industriels\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2024-10-07T16:13:03+01:00\" >7 Octobre 2024<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2024-fr\/wallix-parmi-les-leaders-mondiaux-du-pam-avec-une-mention-speciale-pour-securiser-les-environnements-industriels\/' title='Lier vers : WALLIX parmi les leaders mondiaux du PAM avec une mention sp\u00e9ciale pour s\u00e9curiser les environnements industriels'>WALLIX parmi les leaders mondiaux du PAM avec une mention sp\u00e9ciale pour s\u00e9curiser les environnements industriels<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-61841 av-magazine-format-standard av-magazine-type-post av-magazine-entry-3 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX &amp; Telenor annoncent un partenariat strat\u00e9gique pour renforcer la s\u00e9curit\u00e9 des acc\u00e8s \u00e0 distance dans l&#039;industrie\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2024-09-02T14:51:19+01:00\" >2 Septembre 2024<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2024-fr\/wallix-telenor-annoncent-un-partenariat-strategique-pour-renforcer-la-securite-des-acces-a-distance-dans-lindustrie\/' title='Lier vers : WALLIX &#038; Telenor annoncent un partenariat strat\u00e9gique pour renforcer la s\u00e9curit\u00e9 des acc\u00e8s \u00e0 distance dans l&rsquo;industrie'>WALLIX &#038; Telenor annoncent un partenariat strat\u00e9gique pour renforcer la s\u00e9curit\u00e9 des acc\u00e8s \u00e0 distance dans l&rsquo;industrie<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-59823 av-magazine-format-standard av-magazine-type-post av-magazine-entry-4 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX renforce son partenariat avec CISCO pour cyber s\u00e9curiser les r\u00e9seaux industriels\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2024-06-26T10:31:58+01:00\" >26 Juin 2024<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2024-fr\/wallix-renforce-son-partenariat-avec-cisco-pour-cyber-securiser-les-reseaux-industriels\/' title='Lier vers : WALLIX renforce son partenariat avec CISCO pour cyber s\u00e9curiser les r\u00e9seaux industriels'>WALLIX renforce son partenariat avec CISCO pour cyber s\u00e9curiser les r\u00e9seaux industriels<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-57290 av-magazine-format-standard av-magazine-type-post av-magazine-entry-5 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX poursuit son d\u00e9veloppement au Royaume-Uni en partenariat avec Prianto\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2024-04-23T11:11:46+01:00\" >23 Avril 2024<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/wallix-poursuit-son-developpement-au-royaume-uni-en-partenariat-avec-prianto\/' title='Lier vers : WALLIX poursuit son d\u00e9veloppement au Royaume-Uni en partenariat avec Prianto'>WALLIX poursuit son d\u00e9veloppement au Royaume-Uni en partenariat avec Prianto<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-040bc61f5641f45fc1cf88d91b8f7592\">\n#top .av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 av-special-heading-h3 blockquote modern-quote  avia-builder-el-9  el_after_av_magazine  el_before_av_hr '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Communiqu\u00e9 de presse<\/h3><div class='av-subheading av-subheading_below'><p>2023<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-af89a52d51412774536fa272e468f7cd\">\n#top .hr.hr-invisible.av-av_hr-af89a52d51412774536fa272e468f7cd{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-av_hr-af89a52d51412774536fa272e468f7cd hr-invisible  avia-builder-el-10  el_after_av_heading  el_before_av_magazine '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  id=\"avia-magazine-2\"  class='av-magazine av-ls3ga5mo-c408a2e482d366da7df9be418eb83b35  avia-builder-el-11  el_after_av_hr  el_before_av_heading   avia-builder-el-11  el_after_av_hr  el_before_av_heading ' ><div class='av-magazine-group sort_all'><article class='av-magazine-entry av-magazine-entry-id-38996 av-magazine-format-standard av-magazine-type-post av-magazine-entry-1 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : Lancement de WALLIX One, la plateforme SaaS de cybers\u00e9curit\u00e9 con\u00e7ue pour s&#039;adapter aux enjeux num\u00e9riques et \u00e9conomiques des entreprises qui veulent prot\u00e9ger leurs acc\u00e8s et identit\u00e9s\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2023-12-14T11:29:27+01:00\" >14 D\u00e9cembre 2023<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/lancement-de-wallix-one-la-plateforme-saas-de-cybersecurite-concue-pour-sadapter-aux-enjeux-numeriques-et-economiques-des-entreprises-qui-veulent-proteger-leurs-acces-et-identites\/' title='Lier vers : Lancement de WALLIX One, la plateforme SaaS de cybers\u00e9curit\u00e9 con\u00e7ue pour s&rsquo;adapter aux enjeux num\u00e9riques et \u00e9conomiques des entreprises qui veulent prot\u00e9ger leurs acc\u00e8s et identit\u00e9s'>Lancement de WALLIX One, la plateforme SaaS de cybers\u00e9curit\u00e9 con\u00e7ue pour s&rsquo;adapter aux enjeux num\u00e9riques et \u00e9conomiques des entreprises qui veulent prot\u00e9ger leurs acc\u00e8s et identit\u00e9s<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39000 av-magazine-format-standard av-magazine-type-post av-magazine-entry-2 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : We Edu : WALLIX signe un partenariat avec les IUT et int\u00e8gre sa formation certifiante dans le parcours cybers\u00e9curit\u00e9 du Bachelor Universitaire de Technologie R\u00e9seaux &amp; T\u00e9l\u00e9coms\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2023-09-21T11:32:59+01:00\" >21 Septembre 2023<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/we-edu-wallix-signe-un-partenariat-avec-les-iut-et-integre-sa-formation-certifiante-dans-le-parcours-cybersecurite-du-bachelor-universitaire-de-technologie-reseaux-telecoms\/' title='Lier vers : We Edu : WALLIX signe un partenariat avec les IUT et int\u00e8gre sa formation certifiante dans le parcours cybers\u00e9curit\u00e9 du Bachelor Universitaire de Technologie R\u00e9seaux &#038; T\u00e9l\u00e9coms'>We Edu : WALLIX signe un partenariat avec les IUT et int\u00e8gre sa formation certifiante dans le parcours cybers\u00e9curit\u00e9 du Bachelor Universitaire de Technologie R\u00e9seaux &#038; T\u00e9l\u00e9coms<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39004 av-magazine-format-standard av-magazine-type-post av-magazine-entry-3 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX rejoint le Demo Center OT d&#039;Orange Cyberdefense en France pour montrer comment ses solutions garantissent la r\u00e9silience et la continuit\u00e9 d&#039;activit\u00e9 des syst\u00e8mes industriels en cas de cyberattaque\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2023-07-04T11:36:27+01:00\" >4 Juillet 2023<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-rejoint-le-demo-center-ot-dorange-cyberdefense-en-france-pour-montrer-comment-ses-solutions-garantissent-la-resilience-et-la-continuite-dactivite-des-systemes-industriels-en-cas-de-cyberatt\/' title='Lier vers : WALLIX rejoint le Demo Center OT d&rsquo;Orange Cyberdefense en France pour montrer comment ses solutions garantissent la r\u00e9silience et la continuit\u00e9 d&rsquo;activit\u00e9 des syst\u00e8mes industriels en cas de cyberattaque'>WALLIX rejoint le Demo Center OT d&rsquo;Orange Cyberdefense en France pour montrer comment ses solutions garantissent la r\u00e9silience et la continuit\u00e9 d&rsquo;activit\u00e9 des syst\u00e8mes industriels en cas de cyberattaque<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39008 av-magazine-format-standard av-magazine-type-post av-magazine-entry-4 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX constitue un comit\u00e9 d&#039;experts, utilisateurs prestigieux, pour adapter sa strat\u00e9gie au plus pr\u00e8s des besoins du march\u00e9\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2023-06-27T11:39:27+01:00\" >27 Juin 2023<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-constitue-un-comite-dexperts-utilisateurs-prestigieux-pour-adapter-sa-strategie-au-plus-pres-des-besoins-du-marche\/' title='Lier vers : WALLIX constitue un comit\u00e9 d&rsquo;experts, utilisateurs prestigieux, pour adapter sa strat\u00e9gie au plus pr\u00e8s des besoins du march\u00e9'>WALLIX constitue un comit\u00e9 d&rsquo;experts, utilisateurs prestigieux, pour adapter sa strat\u00e9gie au plus pr\u00e8s des besoins du march\u00e9<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39012 av-magazine-format-standard av-magazine-type-post av-magazine-entry-5 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : Cris R\u00e9seaux va distribuer WALLIX One IDaaS pour rendre la gestion des identit\u00e9s et des acc\u00e8s num\u00e9riques en mode SaaS accessible aux PME\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2023-06-20T11:43:39+01:00\" >20 Juin 2023<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/cris-reseaux-va-distribuer-wallix-one-idaas-pour-rendre-la-gestion-des-identites-et-des-acces-numeriques-en-mode-saas-accessible-aux-pme\/' title='Lier vers : Cris R\u00e9seaux va distribuer WALLIX One IDaaS pour rendre la gestion des identit\u00e9s et des acc\u00e8s num\u00e9riques en mode SaaS accessible aux PME'>Cris R\u00e9seaux va distribuer WALLIX One IDaaS pour rendre la gestion des identit\u00e9s et des acc\u00e8s num\u00e9riques en mode SaaS accessible aux PME<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-040bc61f5641f45fc1cf88d91b8f7592\">\n#top .av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-040bc61f5641f45fc1cf88d91b8f7592 av-special-heading-h3 blockquote modern-quote  avia-builder-el-12  el_after_av_magazine  el_before_av_hr '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Communiqu\u00e9 de presse<\/h3><div class='av-subheading av-subheading_below'><p>2022<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_hr-3cdc9664f29087702913853352eac422\">\n#top .hr.hr-invisible.av-av_hr-3cdc9664f29087702913853352eac422{\nheight:10px;\n}\n<\/style>\n<div  class='hr av-av_hr-3cdc9664f29087702913853352eac422 hr-invisible  avia-builder-el-13  el_after_av_heading  el_before_av_magazine '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n<div  id=\"avia-magazine-3\"  class='av-magazine av-ls3g9uh9-bac0bc988cee21e6e8bf922ac638000b  avia-builder-el-14  el_after_av_hr  avia-builder-el-last   avia-builder-el-14  el_after_av_hr  avia-builder-el-last ' ><div class='av-magazine-group sort_all'><article class='av-magazine-entry av-magazine-entry-id-56859 av-magazine-format-standard av-magazine-type-post av-magazine-entry-1 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX et NOZOMI NETWORKS signent une alliance technologique pour renforcer la cybers\u00e9curit\u00e9 de l&#039;industrie\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2024-04-17T14:05:18+01:00\" >17 Avril 2024<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2022-fr\/wallix-et-nozomi-networks-signent-une-alliance-technologique-pour-renforcer-la-cybersecurite-de-lindustrie\/' title='Lier vers : WALLIX et NOZOMI NETWORKS signent une alliance technologique pour renforcer la cybers\u00e9curit\u00e9 de l&rsquo;industrie'>WALLIX et NOZOMI NETWORKS signent une alliance technologique pour renforcer la cybers\u00e9curit\u00e9 de l&rsquo;industrie<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-27758 av-magazine-format-standard av-magazine-type-post av-magazine-entry-2 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX est reconnu parmi les leaders mondiaux du PAM par le cabinet d&#039;analystes Quadrant Knowledge Solutions\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2022-10-27T16:00:10+01:00\" >27 Octobre 2022<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/wallix-reconnu-leaders-pam-cabinet-quadrant-knowledge-solutions\/' title='Lier vers : WALLIX est reconnu parmi les leaders mondiaux du PAM par le cabinet d&rsquo;analystes Quadrant Knowledge Solutions'>WALLIX est reconnu parmi les leaders mondiaux du PAM par le cabinet d&rsquo;analystes Quadrant Knowledge Solutions<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39074 av-magazine-format-standard av-magazine-type-post av-magazine-entry-3 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX acc\u00e9l\u00e8re sur le march\u00e9 de l&#039;industrie en lan\u00e7ant OT.security by WALLIX, sa marque d\u00e9di\u00e9e \u00e0 la cybers\u00e9curit\u00e9 industrielle\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2022-10-06T15:39:32+01:00\" >6 Octobre 2022<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2022-fr\/wallix-accelere-sur-le-marche-de-lindustrie-en-lancant-ot-security-by-wallix-sa-marque-dediee-a-la-cybersecurite-industrielle\/' title='Lier vers : WALLIX acc\u00e9l\u00e8re sur le march\u00e9 de l&rsquo;industrie en lan\u00e7ant OT.security by WALLIX, sa marque d\u00e9di\u00e9e \u00e0 la cybers\u00e9curit\u00e9 industrielle'>WALLIX acc\u00e9l\u00e8re sur le march\u00e9 de l&rsquo;industrie en lan\u00e7ant OT.security by WALLIX, sa marque d\u00e9di\u00e9e \u00e0 la cybers\u00e9curit\u00e9 industrielle<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39078 av-magazine-format-standard av-magazine-type-post av-magazine-entry-4 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX rejoint OPEN XDR PLATFORM pour l&#039;\u00e9tendre \u00e0 la s\u00e9curit\u00e9 des acc\u00e8s et des identit\u00e9s num\u00e9riques\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2022-09-06T15:51:41+01:00\" >6 Septembre 2022<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/communique-de-presse\/2022-fr\/wallix-rejoint-open-xdr-platform-pour-letendre-a-la-securite-des-acces-et-des-identites-numeriques\/' title='Lier vers : WALLIX rejoint OPEN XDR PLATFORM pour l&rsquo;\u00e9tendre \u00e0 la s\u00e9curit\u00e9 des acc\u00e8s et des identit\u00e9s num\u00e9riques'>WALLIX rejoint OPEN XDR PLATFORM pour l&rsquo;\u00e9tendre \u00e0 la s\u00e9curit\u00e9 des acc\u00e8s et des identit\u00e9s num\u00e9riques<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><article class='av-magazine-entry av-magazine-entry-id-39096 av-magazine-format-standard av-magazine-type-post av-magazine-entry-5 av-magazine-entry-small av-magazine-no-thumb'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"av-magazine-content-wrap\"><header class=\"entry-content-header\" aria-label=\"Articles : WALLIX PAM est reconnue comme la meilleure solution PAM du march\u00e9 par le cabinet d&#039;analystes am\u00e9ricain Frost &amp; Sullivan\"><time class='av-magazine-time updated'  itemprop=\"datePublished\" datetime=\"2022-06-20T16:01:33+01:00\" >20 Juin 2022<\/time><h3 class='av-magazine-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.wallix.com\/fr\/blogpost\/wallix-pam4all-est-reconnue-comme-la-meilleure-solution-pam-du-marche-par-le-cabinet-danalystes-americain-frost-sullivan\/' title='Lier vers : WALLIX PAM est reconnue comme la meilleure solution PAM du march\u00e9 par le cabinet d&rsquo;analystes am\u00e9ricain Frost &#038; Sullivan'>WALLIX PAM est reconnue comme la meilleure solution PAM du march\u00e9 par le cabinet d&rsquo;analystes am\u00e9ricain Frost &#038; Sullivan<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><\/p><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[2053,2174],"tags":[],"class_list":["post-39048","post","type-post","status-publish","format-standard","hentry","category-2023-fr","category-communique-de-presse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WALLIX reconnu &quot;Overall Leader&quot; par le cabinet d&#039;analystes KuppingerCole - WALLIX<\/title>\n<meta name=\"description\" content=\"WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait que c&#039;est une solution compl\u00e8te...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WALLIX reconnu &quot;Overall Leader&quot; par le cabinet d&#039;analystes KuppingerCole - WALLIX\" \/>\n<meta property=\"og:description\" content=\"WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait que c&#039;est une solution compl\u00e8te...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/\" \/>\n<meta property=\"og:site_name\" content=\"WALLIX\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T13:41:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T13:58:24+00:00\" \/>\n<meta name=\"author\" content=\"WALLIX\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@wallixcom\" \/>\n<meta name=\"twitter:site\" content=\"@wallixcom\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"WALLIX\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/communique-de-presse\\\/2023-fr\\\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/communique-de-presse\\\/2023-fr\\\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\\\/\"},\"author\":{\"name\":\"WALLIX\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#\\\/schema\\\/person\\\/8b1daa830716a62cdf5631aa0e211abd\"},\"headline\":\"WALLIX reconnu \u00ab\u00a0Overall Leader\u00a0\u00bb par le cabinet d&rsquo;analystes KuppingerCole\",\"datePublished\":\"2023-01-19T13:41:35+00:00\",\"dateModified\":\"2025-11-18T13:58:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/communique-de-presse\\\/2023-fr\\\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\\\/\"},\"wordCount\":2879,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#organization\"},\"articleSection\":[\"2023\",\"COMMUNIQU\u00c9S DE PRESSE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/communique-de-presse\\\/2023-fr\\\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\\\/\",\"url\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/communique-de-presse\\\/2023-fr\\\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\\\/\",\"name\":\"WALLIX reconnu \\\"Overall Leader\\\" par le cabinet d'analystes KuppingerCole - WALLIX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-01-19T13:41:35+00:00\",\"dateModified\":\"2025-11-18T13:58:24+00:00\",\"description\":\"WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait que c'est une solution compl\u00e8te...\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wallix.com\\\/fr\\\/communique-de-presse\\\/2023-fr\\\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/\",\"name\":\"WALLIX\",\"description\":\"CYBERSECURITY SIMPLIFIED\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#organization\",\"name\":\"WALLIX\",\"url\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wallix.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/LOGO_WALLIX_2024_blackorange.png\",\"contentUrl\":\"https:\\\/\\\/www.wallix.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/LOGO_WALLIX_2024_blackorange.png\",\"width\":3108,\"height\":827,\"caption\":\"WALLIX\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/wallixcom\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wallix\\\/\",\"https:\\\/\\\/www.youtube.com\\\/wallix\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/#\\\/schema\\\/person\\\/8b1daa830716a62cdf5631aa0e211abd\",\"name\":\"WALLIX\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bf1123a19c4364709de2f7c8c881ed5f2bb750cac73f782f39aea052e526546?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bf1123a19c4364709de2f7c8c881ed5f2bb750cac73f782f39aea052e526546?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bf1123a19c4364709de2f7c8c881ed5f2bb750cac73f782f39aea052e526546?s=96&d=mm&r=g\",\"caption\":\"WALLIX\"},\"url\":\"https:\\\/\\\/www.wallix.com\\\/fr\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WALLIX reconnu \"Overall Leader\" par le cabinet d'analystes KuppingerCole - WALLIX","description":"WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait que c'est une solution compl\u00e8te...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/","og_locale":"fr_FR","og_type":"article","og_title":"WALLIX reconnu \"Overall Leader\" par le cabinet d'analystes KuppingerCole - WALLIX","og_description":"WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait que c'est une solution compl\u00e8te...","og_url":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/","og_site_name":"WALLIX","article_published_time":"2023-01-19T13:41:35+00:00","article_modified_time":"2025-11-18T13:58:24+00:00","author":"WALLIX","twitter_card":"summary_large_image","twitter_creator":"@wallixcom","twitter_site":"@wallixcom","twitter_misc":{"\u00c9crit par":"WALLIX","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/#article","isPartOf":{"@id":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/"},"author":{"name":"WALLIX","@id":"https:\/\/www.wallix.com\/fr\/#\/schema\/person\/8b1daa830716a62cdf5631aa0e211abd"},"headline":"WALLIX reconnu \u00ab\u00a0Overall Leader\u00a0\u00bb par le cabinet d&rsquo;analystes KuppingerCole","datePublished":"2023-01-19T13:41:35+00:00","dateModified":"2025-11-18T13:58:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/"},"wordCount":2879,"publisher":{"@id":"https:\/\/www.wallix.com\/fr\/#organization"},"articleSection":["2023","COMMUNIQU\u00c9S DE PRESSE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/","url":"https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/","name":"WALLIX reconnu \"Overall Leader\" par le cabinet d'analystes KuppingerCole - WALLIX","isPartOf":{"@id":"https:\/\/www.wallix.com\/fr\/#website"},"datePublished":"2023-01-19T13:41:35+00:00","dateModified":"2025-11-18T13:58:24+00:00","description":"WALLIX PAM a obtenu des \u00e9valuations quasi maximales selon les crit\u00e8res de KuppingerCole qui reconnait que c'est une solution compl\u00e8te...","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wallix.com\/fr\/communique-de-presse\/2023-fr\/wallix-reconnu-overall-leader-par-le-cabinet-danalystes-kuppingercole\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.wallix.com\/fr\/#website","url":"https:\/\/www.wallix.com\/fr\/","name":"WALLIX","description":"CYBERSECURITY SIMPLIFIED","publisher":{"@id":"https:\/\/www.wallix.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wallix.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wallix.com\/fr\/#organization","name":"WALLIX","url":"https:\/\/www.wallix.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wallix.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.wallix.com\/wp-content\/uploads\/2024\/03\/LOGO_WALLIX_2024_blackorange.png","contentUrl":"https:\/\/www.wallix.com\/wp-content\/uploads\/2024\/03\/LOGO_WALLIX_2024_blackorange.png","width":3108,"height":827,"caption":"WALLIX"},"image":{"@id":"https:\/\/www.wallix.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/wallixcom","https:\/\/www.linkedin.com\/company\/wallix\/","https:\/\/www.youtube.com\/wallix"]},{"@type":"Person","@id":"https:\/\/www.wallix.com\/fr\/#\/schema\/person\/8b1daa830716a62cdf5631aa0e211abd","name":"WALLIX","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/8bf1123a19c4364709de2f7c8c881ed5f2bb750cac73f782f39aea052e526546?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8bf1123a19c4364709de2f7c8c881ed5f2bb750cac73f782f39aea052e526546?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8bf1123a19c4364709de2f7c8c881ed5f2bb750cac73f782f39aea052e526546?s=96&d=mm&r=g","caption":"WALLIX"},"url":"https:\/\/www.wallix.com\/fr\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/posts\/39048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/comments?post=39048"}],"version-history":[{"count":11,"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/posts\/39048\/revisions"}],"predecessor-version":[{"id":80824,"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/posts\/39048\/revisions\/80824"}],"wp:attachment":[{"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/media?parent=39048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/categories?post=39048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wallix.com\/fr\/wp-json\/wp\/v2\/tags?post=39048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}